{"id":3560,"date":"2020-01-10T13:15:20","date_gmt":"2020-01-10T11:15:20","guid":{"rendered":"https:\/\/egypt-era.org\/?page_id=3560"},"modified":"2020-01-10T13:47:35","modified_gmt":"2020-01-10T11:47:35","slug":"access-11-graduation-ceremony","status":"publish","type":"page","link":"https:\/\/egypt-era.org\/en\/events\/access-11-graduation-ceremony\/","title":{"rendered":"Access 11 Graduation Ceremony"},"content":{"rendered":"<div id=\"page-header-1990456051\" class=\"page-header-wrapper\">\n  <div class=\"page-title dark featured-title\">\n\n        <div class=\"page-title-bg\">\n      <div class=\"title-bg fill bg-fill\"\n        data-parallax-container=\".page-title\"\n        data-parallax-background\n data-parallax=\"-\">\n      <\/div>\n      <div class=\"title-overlay fill\"><\/div>\n    <\/div>\n    \n    <div class=\"page-title-inner container align-center flex-row medium-flex-wrap\" >\n              <div class=\"title-wrapper flex-col text-left medium-text-center\">\n          <h1 class=\"entry-title mb-0\">\n            Access 11 Graduation Ceremony          <\/h1>\n        <\/div>\n                    <div class=\"title-content flex-col flex-right text-right medium-text-center\">\n        <div class=\"title-breadcrumbs pb-half pt-half\"><\/div>      <\/div>\n    <\/div><!-- flex-row -->\n\n     \n<style scope=\"scope\">\n\n#page-header-1990456051 .title-bg {\n  background-image: url(https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/08\/unsplash3-4-of-4.jpg);\n  background-position: 67% 51%;\n}\n#page-header-1990456051 .title-overlay {\n  background-color: rgba(0, 0, 0, 0.5);\n}\n<\/style>\n  <\/div><!-- .page-title -->\n    <\/div><!-- .page-header-wrapper -->\n  \n<div class=\"gap-element clearfix\" style=\"display:block; height:auto; padding-top:30px\"><\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Gallery<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n  <style scope=\"scope\">\n    #gallery-1627299566 .grid-col-1{height: 600px}\n    #gallery-1627299566 .grid-col-1-2{height: 300px}\n    #gallery-1627299566 .grid-col-1-3{height:200px}\n    #gallery-1627299566 .grid-col-2-3{height: 400px}\n    #gallery-1627299566 .grid-col-1-4{height: 150px}\n    #gallery-1627299566 .grid-col-3-4{height: 450px}\n\n\n        \/* Tablet *\/\n    @media (max-width: 850px){\n      #gallery-1627299566 .grid-col-1{height: 400px}\n      #gallery-1627299566 .grid-col-1-2{height: 200px}\n      #gallery-1627299566 .grid-col-1-3{height:133.33333333333px}\n      #gallery-1627299566 .grid-col-2-3{height: 266.66666666667px}\n      #gallery-1627299566 .grid-col-1-4{height: 100px}\n      #gallery-1627299566 .grid-col-3-4{height: 300px}\n    }\n    \n        \/* Mobile *\/\n    @media (max-width: 550px){\n      #gallery-1627299566 .grid-col-1{height: 400px}\n      #gallery-1627299566 .grid-col-1-2{height: 200px}\n      #gallery-1627299566 .grid-col-1-3{height:133.33333333333px}\n      #gallery-1627299566 .grid-col-2-3{height: 266.66666666667px}\n      #gallery-1627299566 .grid-col-1-4{height: 100px}\n      #gallery-1627299566 .grid-col-3-4{height: 300px}\n    }\n    \n\n  <\/style>\n  \n  \n    <div id=\"gallery-1627299566\" class=\"row row-collapse row-grid\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n          <div class=\"gallery-col col grid-col grid-col-1 large-12 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a1b22d9-38ba-42ec-ac2a-8be846803fbe-1024x682.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"1020\" height=\"679\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a1b22d9-38ba-42ec-ac2a-8be846803fbe-1024x682.jpeg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a1b22d9-38ba-42ec-ac2a-8be846803fbe-1024x682.jpeg 1024w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a1b22d9-38ba-42ec-ac2a-8be846803fbe-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a1b22d9-38ba-42ec-ac2a-8be846803fbe-768x512.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a1b22d9-38ba-42ec-ac2a-8be846803fbe.jpeg 1280w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/32c5dae2-ae13-4565-bb84-3cabbdacb88d-1024x682.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/32c5dae2-ae13-4565-bb84-3cabbdacb88d-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/32c5dae2-ae13-4565-bb84-3cabbdacb88d-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/32c5dae2-ae13-4565-bb84-3cabbdacb88d-1024x682.jpeg 1024w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/32c5dae2-ae13-4565-bb84-3cabbdacb88d-768x512.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/32c5dae2-ae13-4565-bb84-3cabbdacb88d.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/5edcc875-8349-4543-9848-c2f87bf7aef5-1024x682.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/5edcc875-8349-4543-9848-c2f87bf7aef5-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/5edcc875-8349-4543-9848-c2f87bf7aef5-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/5edcc875-8349-4543-9848-c2f87bf7aef5-1024x682.jpeg 1024w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/5edcc875-8349-4543-9848-c2f87bf7aef5-768x512.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/5edcc875-8349-4543-9848-c2f87bf7aef5.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/868c5b99-6735-4ff5-ad50-8408a220c50d.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"148\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/868c5b99-6735-4ff5-ad50-8408a220c50d-300x148.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/868c5b99-6735-4ff5-ad50-8408a220c50d-300x148.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/868c5b99-6735-4ff5-ad50-8408a220c50d-768x378.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/868c5b99-6735-4ff5-ad50-8408a220c50d.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/1c970d96-9194-4f04-a6fc-57ed3a8d27a1.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/1c970d96-9194-4f04-a6fc-57ed3a8d27a1-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/1c970d96-9194-4f04-a6fc-57ed3a8d27a1-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/1c970d96-9194-4f04-a6fc-57ed3a8d27a1-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/1c970d96-9194-4f04-a6fc-57ed3a8d27a1.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/0b97d628-6980-4b49-9ef8-ec4251064442.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"212\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/0b97d628-6980-4b49-9ef8-ec4251064442-300x212.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/0b97d628-6980-4b49-9ef8-ec4251064442-300x212.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/0b97d628-6980-4b49-9ef8-ec4251064442-768x542.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/0b97d628-6980-4b49-9ef8-ec4251064442.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fecf0a86-59c9-4df3-83f8-4d06a23ba4ec.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fecf0a86-59c9-4df3-83f8-4d06a23ba4ec-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fecf0a86-59c9-4df3-83f8-4d06a23ba4ec-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fecf0a86-59c9-4df3-83f8-4d06a23ba4ec-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fecf0a86-59c9-4df3-83f8-4d06a23ba4ec.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/7fd52c94-332b-4695-9aba-d1fb06a1df86.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/7fd52c94-332b-4695-9aba-d1fb06a1df86-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/7fd52c94-332b-4695-9aba-d1fb06a1df86-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/7fd52c94-332b-4695-9aba-d1fb06a1df86-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/7fd52c94-332b-4695-9aba-d1fb06a1df86.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fdb0b3a0-502c-4137-81b6-8399824007bc.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"224\" height=\"300\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fdb0b3a0-502c-4137-81b6-8399824007bc-224x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fdb0b3a0-502c-4137-81b6-8399824007bc-224x300.jpeg 224w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fdb0b3a0-502c-4137-81b6-8399824007bc.jpeg 717w\" sizes=\"(max-width: 224px) 100vw, 224px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/eec56d9f-98f9-4323-b6c7-17f459e00c89.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"227\" height=\"300\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/eec56d9f-98f9-4323-b6c7-17f459e00c89-227x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/eec56d9f-98f9-4323-b6c7-17f459e00c89-227x300.jpeg 227w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/eec56d9f-98f9-4323-b6c7-17f459e00c89.jpeg 727w\" sizes=\"(max-width: 227px) 100vw, 227px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/a3626364-c160-4c87-853b-a104a0615a24.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/a3626364-c160-4c87-853b-a104a0615a24-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/a3626364-c160-4c87-853b-a104a0615a24-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/a3626364-c160-4c87-853b-a104a0615a24-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/a3626364-c160-4c87-853b-a104a0615a24.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fe23bd6e-5029-4324-9457-b290124a5bf6.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fe23bd6e-5029-4324-9457-b290124a5bf6-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fe23bd6e-5029-4324-9457-b290124a5bf6-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fe23bd6e-5029-4324-9457-b290124a5bf6-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/fe23bd6e-5029-4324-9457-b290124a5bf6.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/181ea99d-cc13-4693-8fd6-f8d4582a1c4e.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/181ea99d-cc13-4693-8fd6-f8d4582a1c4e-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/181ea99d-cc13-4693-8fd6-f8d4582a1c4e-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/181ea99d-cc13-4693-8fd6-f8d4582a1c4e-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/181ea99d-cc13-4693-8fd6-f8d4582a1c4e.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/c70ed5b4-b73d-4e9c-9e0f-4f56c8f4c4e9.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"265\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/c70ed5b4-b73d-4e9c-9e0f-4f56c8f4c4e9-300x265.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/c70ed5b4-b73d-4e9c-9e0f-4f56c8f4c4e9-300x265.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/c70ed5b4-b73d-4e9c-9e0f-4f56c8f4c4e9-768x678.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/c70ed5b4-b73d-4e9c-9e0f-4f56c8f4c4e9.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/15d3f516-0386-4cb2-9823-4569f36e5451.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"139\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/15d3f516-0386-4cb2-9823-4569f36e5451-300x139.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/15d3f516-0386-4cb2-9823-4569f36e5451-300x139.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/15d3f516-0386-4cb2-9823-4569f36e5451-768x357.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/15d3f516-0386-4cb2-9823-4569f36e5451.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/80687e7c-5a69-40a0-8eed-a2312b030f3a.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/80687e7c-5a69-40a0-8eed-a2312b030f3a-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/80687e7c-5a69-40a0-8eed-a2312b030f3a-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/80687e7c-5a69-40a0-8eed-a2312b030f3a-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/80687e7c-5a69-40a0-8eed-a2312b030f3a.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/634cbd16-de05-4106-b429-8659b0825434-1024x682.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/634cbd16-de05-4106-b429-8659b0825434-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/634cbd16-de05-4106-b429-8659b0825434-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/634cbd16-de05-4106-b429-8659b0825434-1024x682.jpeg 1024w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/634cbd16-de05-4106-b429-8659b0825434-768x512.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/634cbd16-de05-4106-b429-8659b0825434.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/bad59344-6055-499f-b188-1a3bbaf1d16f.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/bad59344-6055-499f-b188-1a3bbaf1d16f-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/bad59344-6055-499f-b188-1a3bbaf1d16f-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/bad59344-6055-499f-b188-1a3bbaf1d16f-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/bad59344-6055-499f-b188-1a3bbaf1d16f.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/476fa9e8-bf46-481c-aaf7-9a684c200ecf.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/476fa9e8-bf46-481c-aaf7-9a684c200ecf-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/476fa9e8-bf46-481c-aaf7-9a684c200ecf-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/476fa9e8-bf46-481c-aaf7-9a684c200ecf-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/476fa9e8-bf46-481c-aaf7-9a684c200ecf.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/57cb2308-8a09-4521-bf6b-ce050f404841.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/57cb2308-8a09-4521-bf6b-ce050f404841-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/57cb2308-8a09-4521-bf6b-ce050f404841-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/57cb2308-8a09-4521-bf6b-ce050f404841-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/57cb2308-8a09-4521-bf6b-ce050f404841.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/1fa2c0fb-aab6-423c-8cf1-e631fdc335da.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/1fa2c0fb-aab6-423c-8cf1-e631fdc335da-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/1fa2c0fb-aab6-423c-8cf1-e631fdc335da-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/1fa2c0fb-aab6-423c-8cf1-e631fdc335da-768x512.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/1fa2c0fb-aab6-423c-8cf1-e631fdc335da.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/a22acabb-fb90-4aed-b660-ec3639b9c17d.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/a22acabb-fb90-4aed-b660-ec3639b9c17d-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/a22acabb-fb90-4aed-b660-ec3639b9c17d-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/a22acabb-fb90-4aed-b660-ec3639b9c17d-768x511.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/a22acabb-fb90-4aed-b660-ec3639b9c17d.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a54b838-fd54-4d27-87e0-e2c492e29ce9-1024x682.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a54b838-fd54-4d27-87e0-e2c492e29ce9-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a54b838-fd54-4d27-87e0-e2c492e29ce9-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a54b838-fd54-4d27-87e0-e2c492e29ce9-1024x682.jpeg 1024w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a54b838-fd54-4d27-87e0-e2c492e29ce9-768x512.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/8a54b838-fd54-4d27-87e0-e2c492e29ce9.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/6b0d2360-8b1f-4c49-abf8-561d2dc2a660-1024x576.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"169\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/6b0d2360-8b1f-4c49-abf8-561d2dc2a660-300x169.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/6b0d2360-8b1f-4c49-abf8-561d2dc2a660-300x169.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/6b0d2360-8b1f-4c49-abf8-561d2dc2a660-1024x576.jpeg 1024w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/6b0d2360-8b1f-4c49-abf8-561d2dc2a660-768x432.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/6b0d2360-8b1f-4c49-abf8-561d2dc2a660.jpeg 1040w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/55d2367d-fc5a-484a-8e83-fad9f7abefa0.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"239\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/55d2367d-fc5a-484a-8e83-fad9f7abefa0-300x239.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/55d2367d-fc5a-484a-8e83-fad9f7abefa0-300x239.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/55d2367d-fc5a-484a-8e83-fad9f7abefa0-768x612.jpeg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/55d2367d-fc5a-484a-8e83-fad9f7abefa0.jpeg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/aec590a1-efc6-4388-ae11-cf06fb21e33d.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/aec590a1-efc6-4388-ae11-cf06fb21e33d-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/aec590a1-efc6-4388-ae11-cf06fb21e33d-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/aec590a1-efc6-4388-ae11-cf06fb21e33d.jpeg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/b006c7fb-b265-473c-834c-e6ff20461ada.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/b006c7fb-b265-473c-834c-e6ff20461ada-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/b006c7fb-b265-473c-834c-e6ff20461ada-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/b006c7fb-b265-473c-834c-e6ff20461ada.jpeg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col grid-col grid-col-1-3 large-4 medium-12\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/58e2bbdb-06b3-432e-9103-0f1ac6ee4e5b.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark box-text-center\">\n              <div class=\"box-image\" >\n                <img width=\"300\" height=\"200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/58e2bbdb-06b3-432e-9103-0f1ac6ee4e5b-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"3562,3564,3566,3568,3570,3572,3574,3576,3578,3580,3582,3584,3586,3588,3590,3592,3594,3596,3598,3600,3602,3604,3606,3608,3610,3612,3614,3616\" style=\"default\" type=\"grid\" grid=\"2\" col_spacing=\"collapse\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/58e2bbdb-06b3-432e-9103-0f1ac6ee4e5b-300x200.jpeg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2020\/01\/58e2bbdb-06b3-432e-9103-0f1ac6ee4e5b.jpeg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left dark\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n         <\/div>\n<div class=\"gap-element clearfix\" style=\"display:block; height:auto; padding-top:30px\"><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3608,"parent":2099,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":[],"_links":{"self":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/3560"}],"collection":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/comments?post=3560"}],"version-history":[{"count":2,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/3560\/revisions"}],"predecessor-version":[{"id":3618,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/3560\/revisions\/3618"}],"up":[{"embeddable":true,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/2099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/media\/3608"}],"wp:attachment":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/media?parent=3560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}