{"id":258,"date":"2019-05-13T23:35:48","date_gmt":"2019-05-13T23:35:48","guid":{"rendered":"https:\/\/egypt-era.org\/?page_id=258"},"modified":"2019-09-12T13:21:58","modified_gmt":"2019-09-12T11:21:58","slug":"%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac-%d8%a7%d9%84%d8%ac%d8%b3%d8%b1","status":"publish","type":"page","link":"https:\/\/egypt-era.org\/en\/%d9%85%d8%b4%d8%b1%d9%88%d8%b9%d8%a7%d8%aa%d9%86%d8%a7\/%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac-%d8%a7%d9%84%d8%ac%d8%b3%d8%b1\/","title":{"rendered":"\u0628\u0631\u0646\u0627\u0645\u062c \u0627\u0644\u062c\u0633\u0631"},"content":{"rendered":"<div id=\"page-header-145469191\" class=\"page-header-wrapper\">\n  <div class=\"page-title dark normal-title\">\n\n        <div class=\"page-title-bg\">\n      <div class=\"title-bg fill bg-fill\"\n        data-parallax-container=\".page-title\"\n        data-parallax-background\n data-parallax=\"-\">\n      <\/div>\n      <div class=\"title-overlay fill\"><\/div>\n    <\/div>\n    \n    <div class=\"page-title-inner container align-center text-center flex-row-col medium-flex-wrap\" >\n              <div class=\"title-wrapper uppercase is-large flex-col\">\n          <h1 class=\"entry-title mb-0\">\n            \u0628\u0631\u0646\u0627\u0645\u062c \u0627\u0644\u062c\u0633\u0631          <\/h1>\n        <\/div>\n                    <div class=\"title-content flex-col\">\n        <div class=\"title-breadcrumbs pb-half pt-half\"><\/div>      <\/div>\n    <\/div><!-- flex-row -->\n\n     \n<style scope=\"scope\">\n\n#page-header-145469191 .title-bg {\n  background-image: url(https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/KjdBLIpfIn4w7.jpg);\n}\n<\/style>\n  <\/div><!-- .page-title -->\n    <\/div><!-- .page-header-wrapper -->\n  \n<div class=\"gap-element clearfix\" style=\"display:block; height:auto; padding-top:100px\"><\/div>\n<p><span style=\"font-size: 120%;\">\u0628\u0646\u0627\u0621 \u0627\u0644\u0627\u062d\u062a\u0631\u0627\u0645 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u062d\u0648\u0627\u0631 \u0627\u0644\u062f\u0648\u0644\u064a \u0648\u0627\u0644\u062a\u0639\u0644\u064a\u0645 \u0627\u0644\u0639\u0627\u0644\u0645\u064a<\/span><\/p>\n<p><span style=\"font-size: 120%;\">\u064a\u064f\u0634\u0643\u0644 \u0628\u0631\u0646\u0627\u0645\u062c &#8220;\u0628\u0631\u064a\u062f\u062c&#8221; \u062c\u0632\u0621\u064b\u0627 \u0645\u0646 \u0645\u0628\u0627\u062f\u0631\u0629 &#8220;\u0633\u062a\u064a\u0641\u0646\u0632&#8221;\u060c \u0648\u0647\u064a \u0634\u0631\u0627\u0643\u0629 \u0628\u064a\u0646 \u0627\u0644\u0642\u0637\u0627\u0639\u064a\u0646 \u0627\u0644\u0639\u0627\u0645 \u0648\u0627\u0644\u062e\u0627\u0635 \u0648\u062a\u0647\u062f\u0641 \u0625\u0644\u0649 \u0632\u064a\u0627\u062f\u0629 \u0628\u0631\u0627\u0645\u062c \u0627\u0644\u062a\u0628\u0627\u062f\u0644 \u0627\u0644\u062b\u0642\u0627\u0641\u064a \u0628\u064a\u0646 \u0627\u0644\u0634\u0628\u0627\u0628 \u0641\u064a \u0627\u0644\u0648\u0644\u0627\u064a\u0627\u062a \u0627\u0644\u0645\u062a\u062d\u062f\u0629 \u0648\u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637 \u0648\u0634\u0645\u0627\u0644 \u0623\u0641\u0631\u064a\u0642\u064a\u0627 \u0648\u0630\u0644\u0643 \u0643\u0625\u0634\u0627\u062f\u0629 \u062f\u0627\u0626\u0645\u0629 \u0628\u0625\u0631\u062b \u0627\u0644\u0633\u0641\u064a\u0631 \u0643\u0631\u064a\u0633 \u0633\u062a\u064a\u0641\u0646\u0632. \u0643\u0645\u0627 \u062a\u0633\u0639\u0649 \u0627\u0644\u0645\u0628\u0627\u062f\u0631\u0629 \u0625\u0644\u0649 \u0632\u064a\u0627\u062f\u0629 \u0627\u0644\u062a\u0641\u0627\u0647\u0645 \u0628\u064a\u0646 \u0627\u0644\u0634\u0628\u0627\u0628 \u0641\u064a \u0627\u0644\u0645\u062f\u0627\u0631\u0633 \u0627\u0644\u0645\u062a\u0648\u0633\u0637\u0629 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u062a\u0639\u0644\u064a\u0645 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u062b\u0627\u0646\u0648\u064a\u060c \u0648\u062a\u062c\u0647\u064a\u0632 \u062c\u064a\u0644 \u0645\u0646 \u0627\u0644\u0634\u0628\u0627\u0628 \u0630\u0648\u064a \u0627\u0644\u062a\u0641\u0643\u064a\u0631 \u0627\u0644\u0639\u0627\u0644\u0645\u064a \u0628\u0627\u0644\u0645\u0647\u0627\u0631\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u062d\u062a\u0627\u062c\u0648\u0646\u0647\u0627 \u0644\u0644\u0646\u062c\u0627\u062d \u0641\u064a \u0639\u0627\u0644\u0645 \u0648\u062b\u064a\u0642 \u0627\u0644\u062a\u0631\u0627\u0628\u0637.<\/span><\/p>\n<p><span style=\"font-size: 120%;\">\u0648\u0641\u064a \u0638\u0644 \u0628\u0631\u0646\u0627\u0645\u062c \u0628\u0631\u064a\u062f\u062c\u060c \u0642\u0627\u0645\u062a \u0627\u0644\u062c\u0645\u0639\u064a\u0629 \u0627\u0644\u0645\u0635\u0631\u064a\u0629 \u0644\u0645\u0635\u0627\u062f\u0631 \u0627\u0644\u062a\u0639\u0644\u064a\u0645 \u0628\u062a\u0642\u062f\u064a\u0645 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 \u0627\u0644\u0645\u0647\u0646\u064a \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u0648\u0623\u0646\u0634\u0637\u0629 \u0627\u0644\u062a\u0628\u0627\u062f\u0644 \u0627\u0644\u0627\u0641\u062a\u0631\u0627\u0636\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u0645\u0629 \u0639\u0644\u0649 \u0627\u0644\u0645\u0646\u0627\u0647\u062c \u0627\u0644\u062f\u0631\u0627\u0633\u064a\u0629 \u0644\u0644\u0645\u0639\u0644\u0645\u064a\u0646 \u0641\u064a 11 \u062f\u0648\u0644\u0629 \u0641\u064a \u0645\u0646\u0637\u0642\u0629 \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637 \u0648\u0634\u0645\u0627\u0644 \u0623\u0641\u0631\u064a\u0642\u064a\u0627 \u0648\u0646\u0638\u0631\u0627\u0626\u0647\u0645 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a\u064a\u0646. \u0648\u0628\u0639\u062f \u0627\u0644\u0627\u0646\u062a\u0647\u0627\u0621 \u0645\u0646 \u0627\u0644\u062f\u0648\u0631\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0628\u064a\u0629 \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a\u060c \u062a\u0648\u0627\u0635\u0644 \u0627\u062e\u062a\u0635\u0627\u0635\u064a\u0648 \u0627\u0644\u062a\u0648\u0639\u064a\u0629 \u0645\u0639 \u0637\u0644\u0627\u0628\u0647\u0645 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u0623\u0646\u0634\u0637\u0629 \u063a\u064a\u0631 \u0627\u0644\u0645\u062a\u0632\u0627\u0645\u0646\u0629 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0639\u0628\u0631 \u0627\u0644\u0641\u064a\u062f\u064a\u0648 \u0648\u0627\u0644\u0645\u0639\u0627\u0631\u0636 \u0627\u0644\u0645\u062c\u062a\u0645\u0639\u064a\u0629 \u0641\u064a \u0645\u062c\u0627\u0644\u0627\u062a \u0627\u0644\u0628\u064a\u0626\u0629 \u0648\u0627\u0644\u062a\u0631\u0628\u064a\u0629 \u0627\u0644\u0645\u062f\u0646\u064a\u0629 \u0648\u0627\u0644\u062a\u0631\u0627\u062b \u0648\u0627\u0644\u0647\u0648\u064a\u0629 \u0648\u0627\u0644\u062a\u0642\u0627\u0644\u064a\u062f \u0648\u0627\u0644\u0623\u0645\u0646 \u0627\u0644\u063a\u0630\u0627\u0626\u064a \u0648\u0627\u0644\u0641\u0646\u0648\u0646 \u0648\u0627\u0644\u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0625\u0639\u0644\u0627\u0645\u064a.<\/span><\/p>\n<div class=\"gap-element clearfix\" style=\"display:block; height:auto; padding-top:100px\"><\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Project Images<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-2 slider row-slider slider-nav-reveal\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n          <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/KjdBLIpfIn4w7.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"335\" height=\"274\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/KjdBLIpfIn4w7.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"136,260,261,262,263,264,265\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/KjdBLIpfIn4w7.jpg 335w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/KjdBLIpfIn4w7-300x245.jpg 300w\" sizes=\"(max-width: 335px) 100vw, 335px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"3264\" height=\"2448\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"136,260,261,262,263,264,265\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2.jpg 3264w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2-1024x768.jpg 1024w\" sizes=\"(max-width: 3264px) 100vw, 3264px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/0utCTBoOijxD2-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"4608\" height=\"3456\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/0utCTBoOijxD2.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"136,260,261,262,263,264,265\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/0utCTBoOijxD2.jpg 4608w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/0utCTBoOijxD2-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/0utCTBoOijxD2-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/0utCTBoOijxD2-1024x768.jpg 1024w\" sizes=\"(max-width: 4608px) 100vw, 4608px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/LDumtM8oQaWb9-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2448\" height=\"3264\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/LDumtM8oQaWb9.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"136,260,261,262,263,264,265\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/LDumtM8oQaWb9.jpg 2448w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/LDumtM8oQaWb9-225x300.jpg 225w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/LDumtM8oQaWb9-768x1024.jpg 768w\" sizes=\"(max-width: 2448px) 100vw, 2448px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p2R88GoyMNVrr-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"3264\" height=\"2448\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p2R88GoyMNVrr.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"136,260,261,262,263,264,265\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p2R88GoyMNVrr.jpg 3264w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p2R88GoyMNVrr-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p2R88GoyMNVrr-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p2R88GoyMNVrr-1024x768.jpg 1024w\" sizes=\"(max-width: 3264px) 100vw, 3264px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p28vZ6N1a9bri-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"3264\" height=\"2448\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p28vZ6N1a9bri.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"136,260,261,262,263,264,265\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p28vZ6N1a9bri.jpg 3264w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p28vZ6N1a9bri-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p28vZ6N1a9bri-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/p28vZ6N1a9bri-1024x768.jpg 1024w\" sizes=\"(max-width: 3264px) 100vw, 3264px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2-1-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"3264\" height=\"2448\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2-1.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"136,260,261,262,263,264,265\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2-1.jpg 3264w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2-1-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2-1-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/05\/pWnl4i1fJKBS2-1-1024x768.jpg 1024w\" sizes=\"(max-width: 3264px) 100vw, 3264px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n         <\/div>","protected":false},"excerpt":{"rendered":"<p>\u0628\u0646\u0627\u0621 \u0627\u0644\u0627\u062d\u062a\u0631\u0627\u0645 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u062d\u0648\u0627\u0631 \u0627\u0644\u062f\u0648\u0644\u064a \u0648\u0627\u0644\u062a\u0639\u0644\u064a\u0645 \u0627\u0644\u0639\u0627\u0644\u0645\u064a \u064a\u064f\u0634\u0643\u0644 \u0628\u0631\u0646\u0627\u0645\u062c &#8220;\u0628\u0631\u064a\u062f\u062c&#8221; \u062c\u0632\u0621\u064b\u0627 \u0645\u0646 \u0645\u0628\u0627\u062f\u0631\u0629 &#8220;\u0633\u062a\u064a\u0641\u0646\u0632&#8221;\u060c \u0648\u0647\u064a \u0634\u0631\u0627\u0643\u0629 \u0628\u064a\u0646 \u0627\u0644\u0642\u0637\u0627\u0639\u064a\u0646 \u0627\u0644\u0639\u0627\u0645 \u0648\u0627\u0644\u062e\u0627\u0635 \u0648\u062a\u0647\u062f\u0641 \u0625\u0644\u0649 \u0632\u064a\u0627\u062f\u0629 \u0628\u0631\u0627\u0645\u062c \u0627\u0644\u062a\u0628\u0627\u062f\u0644 \u0627\u0644\u062b\u0642\u0627\u0641\u064a \u0628\u064a\u0646 \u0627\u0644\u0634\u0628\u0627\u0628 \u0641\u064a \u0627\u0644\u0648\u0644\u0627\u064a\u0627\u062a \u0627\u0644\u0645\u062a\u062d\u062f\u0629 \u0648\u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637 \u0648\u0634\u0645\u0627\u0644 \u0623\u0641\u0631\u064a\u0642\u064a\u0627 \u0648\u0630\u0644\u0643 \u0643\u0625\u0634\u0627\u062f\u0629 \u062f\u0627\u0626\u0645\u0629 \u0628\u0625\u0631\u062b \u0627\u0644\u0633\u0641\u064a\u0631 \u0643\u0631\u064a\u0633 \u0633\u062a\u064a\u0641\u0646\u0632. \u0643\u0645\u0627 \u062a\u0633\u0639\u0649 \u0627\u0644\u0645\u0628\u0627\u062f\u0631\u0629 \u0625\u0644\u0649 \u0632\u064a\u0627\u062f\u0629 \u0627\u0644\u062a\u0641\u0627\u0647\u0645 \u0628\u064a\u0646 \u0627\u0644\u0634\u0628\u0627\u0628 \u0641\u064a \u0627\u0644\u0645\u062f\u0627\u0631\u0633 \u0627\u0644\u0645\u062a\u0648\u0633\u0637\u0629 \u0645\u0646 [&#8230;]","protected":false},"author":1,"featured_media":0,"parent":176,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/258"}],"collection":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/comments?post=258"}],"version-history":[{"count":6,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/258\/revisions"}],"predecessor-version":[{"id":1588,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/258\/revisions\/1588"}],"up":[{"embeddable":true,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/176"}],"wp:attachment":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/media?parent=258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}