{"id":2016,"date":"2019-09-20T17:26:05","date_gmt":"2019-09-20T15:26:05","guid":{"rendered":"https:\/\/egypt-era.org\/?page_id=2016"},"modified":"2019-09-20T17:34:03","modified_gmt":"2019-09-20T15:34:03","slug":"%d9%86%d9%87%d8%b1%d9%8a%d9%86-%d9%88%d8%b9%d8%a7%d9%84%d9%85-%d9%88%d8%a7%d8%ad%d8%af","status":"publish","type":"page","link":"https:\/\/egypt-era.org\/en\/%d9%85%d8%b4%d8%b1%d9%88%d8%b9%d8%a7%d8%aa%d9%86%d8%a7\/%d9%86%d9%87%d8%b1%d9%8a%d9%86-%d9%88%d8%b9%d8%a7%d9%84%d9%85-%d9%88%d8%a7%d8%ad%d8%af\/","title":{"rendered":"\u0646\u0647\u0631\u064a\u0646 \u0648\u0639\u0627\u0644\u0645 \u0648\u0627\u062d\u062f"},"content":{"rendered":"<div id=\"page-header-515228280\" class=\"page-header-wrapper\">\n  <div class=\"page-title dark normal-title\">\n\n        <div class=\"page-title-bg\">\n      <div class=\"title-bg fill bg-fill\"\n        data-parallax-container=\".page-title\"\n        data-parallax-background\n data-parallax=\"-\">\n      <\/div>\n      <div class=\"title-overlay fill\"><\/div>\n    <\/div>\n    \n    <div class=\"page-title-inner container align-center text-center flex-row-col medium-flex-wrap\" >\n              <div class=\"title-wrapper uppercase is-large flex-col\">\n          <h1 class=\"entry-title mb-0\">\n            \u0646\u0647\u0631\u064a\u0646 \u0648\u0639\u0627\u0644\u0645 \u0648\u0627\u062d\u062f          <\/h1>\n        <\/div>\n                    <div class=\"title-content flex-col\">\n        <div class=\"title-breadcrumbs pb-half pt-half\"><\/div>      <\/div>\n    <\/div><!-- flex-row -->\n\n     \n<style scope=\"scope\">\n\n#page-header-515228280 .title-bg {\n  background-image: url(https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/solar.jpg);\n  background-position: 45% 0%;\n}\n#page-header-515228280 .title-overlay {\n  background-color: rgba(0,0,0,.5);\n}\n<\/style>\n  <\/div><!-- .page-title -->\n    <\/div><!-- .page-header-wrapper -->\n  \n<div class=\"gap-element clearfix\" style=\"display:block; height:auto; padding-top:100px\"><\/div>\n<p class=\"lead\">\u0643\u0627\u0646 \u0627\u0644\u0647\u062f\u0641 \u0645\u0646 \u0645\u0634\u0631\u0648\u0639&#8221;\u0646\u0647\u0631\u064a\u0646 \u0648\u0639\u0627\u0644\u0645 \u0648\u0627\u062d\u062f&#8221; \u0647\u0648 \u062f\u0639\u0645 \u0637\u0644\u0627\u0628 \u0627\u0644\u0645\u062f\u0627\u0631\u0633 \u0627\u0644\u062b\u0627\u0646\u0648\u064a\u0629 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a\u0629 \u0648\u0627\u0644\u0645\u0635\u0631\u064a\u0629 \u0644\u0644\u0639\u0645\u0644 \u0633\u0648\u064a\u064b\u0627 \u0641\u064a \u0645\u0634\u0631\u0648\u0639 &#8220;\u0646\u0647\u0631\u064a\u0646 \u060c \u0639\u0627\u0644\u0645 \u0648\u0627\u062d\u062f&#8221; \u0627\u0644\u0639\u0644\u0645\u064a. \u0648\u064a\u0631\u0643\u0632 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u0639\u0644\u0649 \u0623\u062e\u0630 \u0648\u062a\u062d\u0644\u064a\u0644 \u0639\u064a\u0646\u0627\u062a \u0645\u0646 \u0646\u0647\u0631\u064a \u0627\u0644\u0646\u064a\u0644 \u0648\u0647\u062f\u0633\u0648\u0646 \u0648\u064a\u0639\u062a\u0645\u062f \u0647\u0630\u0627 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u0639\u0644\u0649 \u062c\u0645\u0639 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0648\u062a\u0633\u062c\u064a\u0644\u0647\u0627 \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u064b\u0627 \u0623\u0648\u0644\u0627\u064b \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a\u060c \u0645\u0646 \u062e\u0644\u0627\u0644 \u0645\u0646\u062a\u062f\u064a\u0627\u062a iEARN \u0627\u0644\u062a\u0641\u0627\u0639\u0644\u064a\u0629 \u060c \u062b\u0645 \u062a\u0645 \u0639\u0642\u062f &#8220;\u0645\u0639\u0633\u0643\u0631 \u0639\u0644\u0645\u064a&#8221; \u0645\u062f\u062a\u0647 \u0623\u0633\u0628\u0648\u0639 \u0648\u0627\u062d\u062f \u0641\u064a \u0645\u0635\u0631.\u00a0<\/p>\n<div class=\"gap-element clearfix\" style=\"display:block; height:auto; padding-top:100px\"><\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Project Images<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-2 slider row-slider slider-nav-reveal\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n          <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/untitled.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"536\" height=\"520\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/untitled.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/untitled.jpg 536w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/untitled-300x291.jpg 300w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01567.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"480\" height=\"640\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01567.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01567.jpg 480w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01567-225x300.jpg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01572.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"640\" height=\"480\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01572.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01572.jpg 640w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01572-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01693-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2592\" height=\"1944\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01693.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01693.jpg 2592w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01693-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01693-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01693-1024x768.jpg 1024w\" sizes=\"(max-width: 2592px) 100vw, 2592px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01695.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"640\" height=\"480\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01695.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01695.jpg 640w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01695-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01710-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2592\" height=\"1944\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01710.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01710.jpg 2592w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01710-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01710-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01710-1024x768.jpg 1024w\" sizes=\"(max-width: 2592px) 100vw, 2592px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01717-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2592\" height=\"1944\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01717.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01717.jpg 2592w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01717-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01717-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/DSC01717-1024x768.jpg 1024w\" sizes=\"(max-width: 2592px) 100vw, 2592px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/H.E.-Undsec.-iEARN-Egypt.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"480\" height=\"360\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/H.E.-Undsec.-iEARN-Egypt.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/H.E.-Undsec.-iEARN-Egypt.jpg 480w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/H.E.-Undsec.-iEARN-Egypt-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0090-1024x766.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2032\" height=\"1520\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0090.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0090.jpg 2032w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0090-300x224.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0090-768x574.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0090-1024x766.jpg 1024w\" sizes=\"(max-width: 2032px) 100vw, 2032px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0115-1024x766.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2032\" height=\"1520\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0115.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0115.jpg 2032w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0115-300x224.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0115-768x574.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0115-1024x766.jpg 1024w\" sizes=\"(max-width: 2032px) 100vw, 2032px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0117-1024x766.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2032\" height=\"1520\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0117.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0117.jpg 2032w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0117-300x224.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0117-768x574.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0117-1024x766.jpg 1024w\" sizes=\"(max-width: 2032px) 100vw, 2032px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0185-1024x766.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2032\" height=\"1520\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0185.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0185.jpg 2032w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0185-300x224.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0185-768x574.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMAG0185-1024x766.jpg 1024w\" sizes=\"(max-width: 2032px) 100vw, 2032px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0062-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"1600\" height=\"1200\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0062.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0062.jpg 1600w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0062-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0062-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0062-1024x768.jpg 1024w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0224-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2048\" height=\"1536\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0224.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0224.jpg 2048w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0224-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0224-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_0224-1024x768.jpg 1024w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7845-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2048\" height=\"1536\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7845.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7845.jpg 2048w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7845-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7845-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7845-1024x768.jpg 1024w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7867-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2048\" height=\"1536\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7867.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7867.jpg 2048w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7867-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7867-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7867-1024x768.jpg 1024w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7941-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2048\" height=\"1536\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7941.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7941.jpg 2048w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7941-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7941-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7941-1024x768.jpg 1024w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7959-768x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"1536\" height=\"2048\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7959.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7959.jpg 1536w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7959-225x300.jpg 225w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_7959-768x1024.jpg 768w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8029-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2048\" height=\"1536\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8029.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8029.jpg 2048w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8029-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8029-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8029-1024x768.jpg 1024w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8103-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"2048\" height=\"1536\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8103.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8103.jpg 2048w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8103-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8103-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/IMG_8103-1024x768.jpg 1024w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-011.jpg\" title=\"IM000423.JPG\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"640\" height=\"480\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-011.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-011.jpg 640w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-011-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p>IM000423.JPG<\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-014.jpg\" title=\"IM000426.JPG\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"640\" height=\"480\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-014.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-014.jpg 640w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-014-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p>IM000426.JPG<\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-017.jpg\" title=\"IM000429.JPG\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"640\" height=\"480\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-017.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-017.jpg 640w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-017-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p>IM000429.JPG<\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-102.jpg\" title=\"IM000526.JPG\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"640\" height=\"480\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-102.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-102.jpg 640w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-102-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p>IM000526.JPG<\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-116.jpg\" title=\"IM000540.JPG\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"640\" height=\"480\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-116.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-116.jpg 640w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-116-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p>IM000540.JPG<\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-119.jpg\" title=\"IM000543.JPG\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"480\" height=\"640\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-119.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-119.jpg 480w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-119-225x300.jpg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p>IM000543.JPG<\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-151.jpg\" title=\"IM000576.JPG\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"640\" height=\"480\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-151.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-151.jpg 640w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/Picture-151-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p>IM000576.JPG<\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/science.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"640\" height=\"480\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/science.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/science.jpg 640w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/science-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n                 <div class=\"gallery-col col\" data-animate=\"bounceInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/solar-1024x768.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image box-shadow-1 box-shadow-3-hover image-cover\" style=\"padding-top:300px;\">\n                <img width=\"3072\" height=\"2304\" src=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/solar.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" loading=\"lazy\" ids=\"2074,2018,2020,2022,2024,2026,2028,2030,2032,2034,2036,2038,2040,2042,2044,2046,2048,2050,2052,2054,2056,2058,2060,2062,2064,2066,2068,2070,2072\" type=\"slider\" columns=\"3\" depth=\"1\" depth_hover=\"3\" animate=\"bounceInRight\" image_height=\"300px\" image_size=\"original\" srcset=\"https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/solar.jpg 3072w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/solar-300x225.jpg 300w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/solar-768x576.jpg 768w, https:\/\/egypt-era.org\/wp-content\/uploads\/2019\/09\/solar-1024x768.jpg 1024w\" sizes=\"(max-width: 3072px) 100vw, 3072px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div><!-- .image -->\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div><!-- .text -->\n            <\/div><!-- .box -->\n            <\/a>          <\/div><!-- .col-inner -->\n         <\/div><!-- .col -->\n         <\/div>","protected":false},"excerpt":{"rendered":"<p>\u0643\u0627\u0646 \u0627\u0644\u0647\u062f\u0641 \u0645\u0646 \u0645\u0634\u0631\u0648\u0639&#8221;\u0646\u0647\u0631\u064a\u0646 \u0648\u0639\u0627\u0644\u0645 \u0648\u0627\u062d\u062f&#8221; \u0647\u0648 \u062f\u0639\u0645 \u0637\u0644\u0627\u0628 \u0627\u0644\u0645\u062f\u0627\u0631\u0633 \u0627\u0644\u062b\u0627\u0646\u0648\u064a\u0629 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a\u0629 \u0648\u0627\u0644\u0645\u0635\u0631\u064a\u0629 \u0644\u0644\u0639\u0645\u0644 \u0633\u0648\u064a\u064b\u0627 \u0641\u064a \u0645\u0634\u0631\u0648\u0639 &#8220;\u0646\u0647\u0631\u064a\u0646 \u060c \u0639\u0627\u0644\u0645 \u0648\u0627\u062d\u062f&#8221; \u0627\u0644\u0639\u0644\u0645\u064a. \u0648\u064a\u0631\u0643\u0632 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u0639\u0644\u0649 \u0623\u062e\u0630 \u0648\u062a\u062d\u0644\u064a\u0644 \u0639\u064a\u0646\u0627\u062a \u0645\u0646 \u0646\u0647\u0631\u064a \u0627\u0644\u0646\u064a\u0644 \u0648\u0647\u062f\u0633\u0648\u0646 \u0648\u064a\u0639\u062a\u0645\u062f \u0647\u0630\u0627 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u0639\u0644\u0649 \u062c\u0645\u0639 \u0627\u0644\u0628\u064a\u0627\u0646\u0627\u062a \u0648\u062a\u0633\u062c\u064a\u0644\u0647\u0627 \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u064b\u0627 \u0623\u0648\u0644\u0627\u064b \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a\u060c \u0645\u0646 \u062e\u0644\u0627\u0644 \u0645\u0646\u062a\u062f\u064a\u0627\u062a iEARN \u0627\u0644\u062a\u0641\u0627\u0639\u0644\u064a\u0629 \u060c \u062b\u0645 \u062a\u0645 \u0639\u0642\u062f &#8220;\u0645\u0639\u0633\u0643\u0631 \u0639\u0644\u0645\u064a&#8221; \u0645\u062f\u062a\u0647 [&#8230;]","protected":false},"author":1,"featured_media":0,"parent":176,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/2016"}],"collection":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/comments?post=2016"}],"version-history":[{"count":2,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/2016\/revisions"}],"predecessor-version":[{"id":2076,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/2016\/revisions\/2076"}],"up":[{"embeddable":true,"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/pages\/176"}],"wp:attachment":[{"href":"https:\/\/egypt-era.org\/en\/wp-json\/wp\/v2\/media?parent=2016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}